{"id":2285,"date":"2019-11-01T08:53:02","date_gmt":"2019-11-01T08:53:02","guid":{"rendered":"https:\/\/wp-test.getgolo.com\/?post_type=place&#038;p=2285"},"modified":"2026-07-15T20:35:10","modified_gmt":"2026-07-15T20:35:10","slug":"flor","status":"publish","type":"place","link":"https:\/\/golodemodata.uxper.co\/country-guide\/place\/flor\/","title":{"rendered":"Flor Restaurant"},"content":{"rendered":"<p>Flor, in Borough Market, comes with serious credentials; after all, it&#8217;s the long-awaited little sister to the Michelin-starred Lyle\u2019s. Its ground-floor wine bar doubles as a bakery, already known for its sourdough; supplies are limited, so invest in a loaf on arrival. Stools\u2014reserved for walk-ins\u2014line the window and marble counter, which overlooks the kitchen (tiny is an understatement; even four chefs seems a squeeze). Up a spiral staircase, the dining room is surprisingly calm, with a double-height ceiling, bare brick walls, and petrol-blue banquettes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Flor, in Borough Market, comes with serious credentials; after all, it&#8217;s the long-awaited little sister to the Michelin-starred Lyle\u2019s. Its ground-floor wine bar doubles as a bakery, already known for its sourdough; supplies are limited, so invest in a loaf on arrival. Stools\u2014reserved for walk-ins\u2014line the window and marble counter, which overlooks the kitchen (tiny [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":4658,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","place-type":[210],"place-categories":[194],"place-amenities":[184,189,192,206,209,217],"place-city":[207],"class_list":["post-2285","place","type-place","status-publish","has-post-thumbnail","hentry","place-type-restaurants","place-categories-food-drink","place-amenities-air-conditioner","place-amenities-car-parking","place-amenities-credit-cards","place-amenities-non-smoking","place-amenities-reservations","place-amenities-wifi","place-city-paris"],"featured_media_url":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-content\/uploads\/sites\/6\/2019\/11\/photo-1554679665-f5537f187268-540x420-1.jpeg","golo-place_price_short":"","golo-place_price_unit":"m","golo-place_price_range":"3","golo-place_booking_type":"info","golo-place_booking":"","golo-place_booking_site":"","golo-place_booking_2":"","golo-place_booking_site_2":"","golo-place_booking_banner":{"id":"0","url":""},"golo-place_booking_banner_url":"","golo-place_booking_form":"","golo-place_phone":"+44 20 3319 8144","golo-place_phone2":"","golo-place_email":"","golo-place_website":"florlondon.com","golo-place_identity":"2285","golo-google_review_placeid":"","golo-place_facebook":"","golo-place_instagram":"","golo-place_twitter":"","golo-additional_detail":"1","golo-additional_detail_icon":[""],"golo-additional_detail_name":[""],"golo-additional_detail_url":[""],"golo-opening_monday":"Monday","golo-opening_monday_time":"10:00 AM - 11:00 PM","golo-opening_tuesday":"Tuesday","golo-opening_tuesday_time":"10:00 AM - 11:00 PM","golo-opening_wednesday":"Wednesday","golo-opening_wednesday_time":"10:00 AM - 11:00 PM","golo-opening_thursday":"Thursday","golo-opening_thursday_time":"10:00 AM - 11:00 PM","golo-opening_friday":"Friday","golo-opening_friday_time":"10:00 AM - 11:00 PM","golo-opening_saturday":"Saturday","golo-opening_saturday_time":"10:00 AM - 11:00 PM","golo-opening_sunday":"Sunday","golo-opening_sunday_time":"10:00 AM - 11:00 PM","golo-yelp_review":"1","golo-yelp_review_title":["Hotel"],"golo-yelp_review_type":["hotel"],"golo-place_views_count":"10306","golo-menu_enable":"1","golo-menu_types":"2","golo-menu_types_name":["Desserts","Main Course"],"golo-menu_tab":[{"golo-menu_title":"Chiken","golo-menu_price":"$12","golo-menu_description":"Patio dining with many heat lamps","golo-menu_image":{"id":"4958","url":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-content\/uploads\/sites\/6\/2022\/06\/hayley-ryczek-HQ22vVXhWcc-unsplash.jpg"},"golo-menu_item_type":"Desserts"},{"golo-menu_title":"Salad","golo-menu_price":"$8","golo-menu_description":"Patio dining with many heat lamps","golo-menu_image":{"id":"4955","url":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-content\/uploads\/sites\/6\/2022\/06\/anna-pelzer-IGfIGP5ONV0-unsplash.jpg"},"golo-menu_item_type":"Desserts"},{"golo-menu_title":"Pasta Scramble","golo-menu_price":"$9","golo-menu_description":"Patio dining with many heat lamps","golo-menu_image":{"id":"4956","url":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-content\/uploads\/sites\/6\/2022\/06\/Bar-Fisk__2018_bar_fisk_31389-1.jpg"},"golo-menu_item_type":"Desserts"},{"golo-menu_title":"Noodles","golo-menu_price":"$13","golo-menu_description":"Patio dining with many heat lamps","golo-menu_image":{"id":"4959","url":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-content\/uploads\/sites\/6\/2022\/06\/ikhsan-baihaqi-RwAXb8Hv_sU-unsplash.jpg"},"golo-menu_item_type":"Desserts"},{"golo-menu_title":"Fresh Meat","golo-menu_price":"$22","golo-menu_description":"Patio dining with many heat lamps","golo-menu_image":{"id":"4957","url":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-content\/uploads\/sites\/6\/2022\/06\/eiliv-sonas-aceron-YlAmh_X_SsE-unsplash.jpg"},"golo-menu_item_type":"Main Course"},{"golo-menu_title":"Vegetarian Soup","golo-menu_price":"$14","golo-menu_description":"Patio dining with many heat lamps","golo-menu_image":{"id":"4960","url":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-content\/uploads\/sites\/6\/2022\/06\/laura-lanckriet-z32XV0TGSzc-unsplash.jpg"},"golo-menu_item_type":"Main Course"},{"golo-menu_title":"Pizza","golo-menu_price":"$13","golo-menu_description":"Patio dining with many heat lamps","golo-menu_image":{"id":"4962","url":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-content\/uploads\/sites\/6\/2022\/06\/sahal-hameed-Nq9KlQTTEbQ-unsplash.jpg"},"golo-menu_item_type":"Main Course"},{"golo-menu_title":"Nasi Goreng","golo-menu_price":"$22","golo-menu_description":"Patio dining with many heat lamps","golo-menu_image":{"id":"4961","url":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-content\/uploads\/sites\/6\/2022\/06\/mariana-medvedeva-fk6IiypMWss-unsplash.jpg"},"golo-menu_item_type":"Main Course"}],"golo-place_address":"7 Rue Emile Duclaux, 92150 Suresnes, France","golo-place_zip":"","golo-place_timezone":"UTC+0","golo-place_location":{"location":"48.877979,2.2334287"},"golo-place_featured":"0","golo-place_logged":"0","golo-place_images":["https:\/\/golodemodata.uxper.co\/country-guide\/wp-content\/uploads\/sites\/6\/2019\/11\/1.jpeg","https:\/\/golodemodata.uxper.co\/country-guide\/wp-content\/uploads\/sites\/6\/2019\/11\/photo-1490113355845-cdc3b65f0189.jpeg","https:\/\/golodemodata.uxper.co\/country-guide\/wp-content\/uploads\/sites\/6\/2019\/11\/photo-1493564738392-d148cfbd6eda.jpeg","https:\/\/golodemodata.uxper.co\/country-guide\/wp-content\/uploads\/sites\/6\/2022\/06\/The-Dylan-Amsterdam__2018_brasserie_occo_03.jpg"],"golo-place_video_url":"https:\/\/www.youtube.com\/watch?v=nCG8JeNhOGg","golo-place_video_image":"","golo-faqs_enable":"1","golo-faqs_tab":[{"golo-faqs_title":"What it is like to have your first date in this place?","golo-faqs_description":"If you pickup you would need to bring your food home or take it somewhere else to eat it."},{"golo-faqs_title":"How is this business handling reopening?","golo-faqs_description":"Patio dining with many heat lamps and staff all had mask on and clean none stop."}],"golo-booking_item_name":"","golo-booking_item_id":"","golo-booking_item_author":"","golo-booking_adults":"","golo-booking_childrens":"","golo-booking_date":"","golo-booking_time":"","golo-place_coupon":"","golo-package_free":"","golo-package_price":"","golo-package_unlimited_time":"","golo-package_time_unit":"","golo-package_period":"","golo-package_unlimited_listing":"","golo-package_number_listings":"","golo-package_number_featured":"","golo-package_order_display":"","golo-package_featured":"","golo-package_visible":"","golo-package_extra_featured":"","golo-place_rating":"3.7","golo-review_count":4,"_links":{"self":[{"href":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-json\/wp\/v2\/place\/2285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-json\/wp\/v2\/place"}],"about":[{"href":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-json\/wp\/v2\/types\/place"}],"author":[{"embeddable":true,"href":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-json\/wp\/v2\/comments?post=2285"}],"version-history":[{"count":2,"href":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-json\/wp\/v2\/place\/2285\/revisions"}],"predecessor-version":[{"id":4652,"href":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-json\/wp\/v2\/place\/2285\/revisions\/4652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-json\/wp\/v2\/media\/4658"}],"wp:attachment":[{"href":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-json\/wp\/v2\/media?parent=2285"}],"wp:term":[{"taxonomy":"place-type","embeddable":true,"href":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-json\/wp\/v2\/place-type?post=2285"},{"taxonomy":"place-categories","embeddable":true,"href":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-json\/wp\/v2\/place-categories?post=2285"},{"taxonomy":"place-amenities","embeddable":true,"href":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-json\/wp\/v2\/place-amenities?post=2285"},{"taxonomy":"place-city","embeddable":true,"href":"https:\/\/golodemodata.uxper.co\/country-guide\/wp-json\/wp\/v2\/place-city?post=2285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}